{"id":796,"date":"2020-12-08T18:17:01","date_gmt":"2020-12-08T18:17:01","guid":{"rendered":"https:\/\/caanational-rebuild.paperleaftest.com\/au-sujet-de-la-caa\/"},"modified":"2024-05-09T16:05:25","modified_gmt":"2024-05-09T20:05:25","slug":"a-propos-de-nous","status":"publish","type":"page","link":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/","title":{"rendered":"\u00c0 propos de nous"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3200,"parent":1244,"menu_order":162,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-796","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 propos de la CAA - CAA National<\/title>\n<meta name=\"description\" content=\"La CAA est l\u2019une des plus grandes et des plus anciennes organisations de consommateurs au Canada. Informez-vous sur notre association et les clubs que nous f\u00e9d\u00e9rons.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 propos de la CAA - CAA National\" \/>\n<meta property=\"og:description\" content=\"La CAA est l\u2019une des plus grandes et des plus anciennes organisations de consommateurs au Canada. Informez-vous sur notre association et les clubs que nous f\u00e9d\u00e9rons.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"CAA National\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-09T20:05:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caa.ca\/app\/uploads\/2021\/02\/CAA_Toronto_Downtown_Road.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2119\" \/>\n\t<meta property=\"og:image:height\" content=\"932\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/\",\"url\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/\",\"name\":\"\u00c0 propos de la CAA - CAA National\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.caa.ca\\\/app\\\/uploads\\\/2021\\\/02\\\/CAA_Toronto_Downtown_Road.jpg\",\"datePublished\":\"2020-12-08T18:17:01+00:00\",\"dateModified\":\"2024-05-09T20:05:25+00:00\",\"description\":\"La CAA est l\u2019une des plus grandes et des plus anciennes organisations de consommateurs au Canada. Informez-vous sur notre association et les clubs que nous f\u00e9d\u00e9rons.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.caa.ca\\\/app\\\/uploads\\\/2021\\\/02\\\/CAA_Toronto_Downtown_Road.jpg\",\"contentUrl\":\"https:\\\/\\\/www.caa.ca\\\/app\\\/uploads\\\/2021\\\/02\\\/CAA_Toronto_Downtown_Road.jpg\",\"width\":2119,\"height\":932,\"caption\":\"Downtown Toronto Roads\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/home\\\/a-propos-de-nous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c0 propos de nous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/\",\"name\":\"CAA National\",\"description\":\"F\u00e9d\u00e9ration \u00e0 but non lucratif, la CAA offre \u00e0 plus de 6 millions de membres une assistance routi\u00e8re exceptionnelle, des services automobiles, de voyage et d&#039;assurance, et des rabais privil\u00e9gi\u00e9s.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/#organization\",\"name\":\"CAA National\",\"url\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.caa.ca\\\/app\\\/uploads\\\/2020\\\/12\\\/CAA_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.caa.ca\\\/app\\\/uploads\\\/2020\\\/12\\\/CAA_logo.png\",\"width\":2560,\"height\":1749,\"caption\":\"CAA National\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caa.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 propos de la CAA - CAA National","description":"La CAA est l\u2019une des plus grandes et des plus anciennes organisations de consommateurs au Canada. Informez-vous sur notre association et les clubs que nous f\u00e9d\u00e9rons.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 propos de la CAA - CAA National","og_description":"La CAA est l\u2019une des plus grandes et des plus anciennes organisations de consommateurs au Canada. Informez-vous sur notre association et les clubs que nous f\u00e9d\u00e9rons.","og_url":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/","og_site_name":"CAA National","article_modified_time":"2024-05-09T20:05:25+00:00","og_image":[{"width":2119,"height":932,"url":"https:\/\/www.caa.ca\/app\/uploads\/2021\/02\/CAA_Toronto_Downtown_Road.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/","url":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/","name":"\u00c0 propos de la CAA - CAA National","isPartOf":{"@id":"https:\/\/www.caa.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/#primaryimage"},"image":{"@id":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/#primaryimage"},"thumbnailUrl":"https:\/\/www.caa.ca\/app\/uploads\/2021\/02\/CAA_Toronto_Downtown_Road.jpg","datePublished":"2020-12-08T18:17:01+00:00","dateModified":"2024-05-09T20:05:25+00:00","description":"La CAA est l\u2019une des plus grandes et des plus anciennes organisations de consommateurs au Canada. Informez-vous sur notre association et les clubs que nous f\u00e9d\u00e9rons.","breadcrumb":{"@id":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/#primaryimage","url":"https:\/\/www.caa.ca\/app\/uploads\/2021\/02\/CAA_Toronto_Downtown_Road.jpg","contentUrl":"https:\/\/www.caa.ca\/app\/uploads\/2021\/02\/CAA_Toronto_Downtown_Road.jpg","width":2119,"height":932,"caption":"Downtown Toronto Roads"},{"@type":"BreadcrumbList","@id":"https:\/\/www.caa.ca\/fr\/home\/a-propos-de-nous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caa.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Home","item":"https:\/\/www.caa.ca\/fr\/"},{"@type":"ListItem","position":3,"name":"\u00c0 propos de nous"}]},{"@type":"WebSite","@id":"https:\/\/www.caa.ca\/fr\/#website","url":"https:\/\/www.caa.ca\/fr\/","name":"CAA National","description":"F\u00e9d\u00e9ration \u00e0 but non lucratif, la CAA offre \u00e0 plus de 6 millions de membres une assistance routi\u00e8re exceptionnelle, des services automobiles, de voyage et d&#039;assurance, et des rabais privil\u00e9gi\u00e9s.","publisher":{"@id":"https:\/\/www.caa.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caa.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.caa.ca\/fr\/#organization","name":"CAA National","url":"https:\/\/www.caa.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.caa.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.caa.ca\/app\/uploads\/2020\/12\/CAA_logo.png","contentUrl":"https:\/\/www.caa.ca\/app\/uploads\/2020\/12\/CAA_logo.png","width":2560,"height":1749,"caption":"CAA National"},"image":{"@id":"https:\/\/www.caa.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/pages\/796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/comments?post=796"}],"version-history":[{"count":17,"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/pages\/796\/revisions"}],"predecessor-version":[{"id":11189,"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/pages\/796\/revisions\/11189"}],"up":[{"embeddable":true,"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/pages\/1244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/media\/3200"}],"wp:attachment":[{"href":"https:\/\/www.caa.ca\/fr\/wp-json\/wp\/v2\/media?parent=796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}